{"id":56,"date":"2025-03-21T17:09:11","date_gmt":"2025-03-21T08:09:11","guid":{"rendered":"https:\/\/sample.ssrd.jp\/kinder\/?page_id=56"},"modified":"2026-01-28T11:21:20","modified_gmt":"2026-01-28T02:21:20","slug":"access","status":"publish","type":"page","link":"https:\/\/www.educ.kumamoto-u.ac.jp\/kinder\/access\/","title":{"rendered":"\u30a2\u30af\u30bb\u30b9\u30fb\u554f\u5408\u305b"},"content":{"rendered":"<h2 class=\"section_title\">\u30a2\u30af\u30bb\u30b9\u60c5\u5831<\/h2>\r\n<div class=\"access_map_area\">\r\n<div class=\"map_container\">\u00a0<\/div>\r\n<div class=\"access_info\">\r\n<div class=\"access_info_item\">\r\n<h3 class=\"access_info_title\">\u4f4f\u6240\u30fb\u9023\u7d61\u5148<\/h3>\r\n<div class=\"access_info_content\">\r\n<p>\u3012860-0846 \u718a\u672c\u770c\u718a\u672c\u5e02\u4e2d\u592e\u533a\u57ce\u6771\u753a5\u756a9\u53f7<\/p>\r\n<p>TEL 096-352-3483 \/ FAX 096-356-2433<\/p>\r\n<\/div>\r\n<\/div>\r\n<div class=\"access_info_item\">\r\n<h3 class=\"access_info_title\">\u4ea4\u901a\u30a2\u30af\u30bb\u30b9<\/h3>\r\n<div class=\"access_info_content\">\r\n<p>\u718a\u672c\u5e02\u96fb\u300c\u5e02\u5f79\u6240\u524d\u300d\u96fb\u505c\u304b\u3089\u5f92\u6b6910\u5206<\/p>\r\n<p>\u30d0\u30b9\u300c\u901a\u753a\u7b4b\u300d\u30d0\u30b9\u505c\u304b\u3089\u4e0b\u8eca\u5f92\u6b6910\u5206<\/p>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<\/div>\r\n<h2 class=\"section_title\">\u304a\u554f\u3044\u5408\u308f\u305b<\/h2>\r\n<div class=\"contact_info_area\">\r\n<p class=\"contact_description\">\u5f53\u5712\u3078\u306e\u304a\u554f\u3044\u5408\u308f\u305b\u306f\u3001\u4e0b\u8a18\u306e\u96fb\u8a71\u756a\u53f7\u306b\u3066\u304a\u9858\u3044\u3044\u305f\u3057\u307e\u3059\u3002<br \/>\r\n\u53d7\u4ed8\u6642\u9593\uff1a\u5e73\u65e5 9:00\u301c16:00\uff08\u571f\u65e5\u795d\u65e5\u30fb\u5e74\u672b\u5e74\u59cb\u3092\u9664\u304f\uff09<\/p>\r\n<div class=\"contact_info_box\">\r\n<div class=\"contact_info_item\">\r\n<h3 class=\"contact_info_title\">\u96fb\u8a71\u3067\u306e\u304a\u554f\u3044\u5408\u308f\u305b<\/h3>\r\n<p class=\"contact_info_content\">TEL 096-352-3483<\/p>\r\n<\/div>\r\n<\/div>\r\n<\/div>","protected":false},"excerpt":{"rendered":"\u30a2\u30af\u30bb\u30b9\u60c5\u5831 \u00a0 \u4f4f\u6240\u30fb\u9023\u7d61\u5148 \u3012860-0846 \u718a\u672c\u770c\u718a\u672c\u5e02\u4e2d\u592e\u533a\u57ce\u6771\u753a5\u756a9\u53f7 TEL 096-352-3483 \/ FAX 096-356-2433 \u4ea4\u901a\u30a2\u30af\u30bb\u30b9 \u718a\u672c\u5e02\u96fb\u300c\u5e02\u5f79\u6240\u524d\u300d\u96fb\u505c\u304b\u3089\u5f92\u6b6910\u5206 \u30d0\u30b9\u300c\u901a&#8230; <a class=\"view-article\" href=\"https:\/\/www.educ.kumamoto-u.ac.jp\/kinder\/access\/\">View Article<\/a>","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":10,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-56","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.educ.kumamoto-u.ac.jp\/kinder\/wp-json\/wp\/v2\/pages\/56","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.educ.kumamoto-u.ac.jp\/kinder\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.educ.kumamoto-u.ac.jp\/kinder\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.educ.kumamoto-u.ac.jp\/kinder\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.educ.kumamoto-u.ac.jp\/kinder\/wp-json\/wp\/v2\/comments?post=56"}],"version-history":[{"count":6,"href":"https:\/\/www.educ.kumamoto-u.ac.jp\/kinder\/wp-json\/wp\/v2\/pages\/56\/revisions"}],"predecessor-version":[{"id":397,"href":"https:\/\/www.educ.kumamoto-u.ac.jp\/kinder\/wp-json\/wp\/v2\/pages\/56\/revisions\/397"}],"wp:attachment":[{"href":"https:\/\/www.educ.kumamoto-u.ac.jp\/kinder\/wp-json\/wp\/v2\/media?parent=56"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}